{"id":2773,"count":0,"description":"","link":"http:\/\/www.4expedition.com\/blog\/tag\/metal-stamped-parts-4198-87bc77\/","name":"Metal Stamped Parts","slug":"metal-stamped-parts-4198-87bc77","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.4expedition.com\/blog\/wp-json\/wp\/v2\/tags\/2773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.4expedition.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.4expedition.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.4expedition.com\/blog\/wp-json\/wp\/v2\/posts?tags=2773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}